{"id":1070,"date":"2023-01-24T05:13:34","date_gmt":"2023-01-24T05:13:34","guid":{"rendered":"https:\/\/gearrack.top\/china-oem-15062968-auto-spare-parts-steering-rack-for-gmc-savana-2500-3500-duty-gear-rack\/"},"modified":"2023-01-24T05:13:34","modified_gmt":"2023-01-24T05:13:34","slug":"china-oem-15062968-auto-spare-parts-steering-rack-for-gmc-savana-2500-3500-duty-gear-rack","status":"publish","type":"post","link":"https:\/\/gearrack.top\/fr\/china-oem-15062968-auto-spare-parts-steering-rack-for-gmc-savana-2500-3500-duty-gear-rack\/","title":{"rendered":"China OEM 15062968 Auto Spare Parts Steering Rack for Gmc Savana 2500 3500     duty gear rack"},"content":{"rendered":"<p><h2>Solution Description<\/h2>\n<p>\n<p><p>Solution Description<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>Colour<\/td>\n<td>Black<\/td>\n<\/tr>\n<tr>\n<td>E-Waste<\/td>\n<td>No<\/td>\n<\/tr>\n<tr>\n<td>Hose Port Variety<\/td>\n<td>O-Ring<\/td>\n<\/tr>\n<tr>\n<td>Input Shaft Diameter (in)<\/td>\n<td>.seventy three<\/td>\n<\/tr>\n<tr>\n<td>Input Shaft Diameter (mm)<\/td>\n<td>eighteen.42<\/td>\n<\/tr>\n<tr>\n<td>Enter Shaft Spline Count<\/td>\n<td>25 + Flat &amp; Groove<\/td>\n<\/tr>\n<tr>\n<td>Enter Shaft Kind<\/td>\n<td>Splined, One Flat<\/td>\n<\/tr>\n<tr>\n<td>Amount of Mounting Holes<\/td>\n<td>3<\/td>\n<\/tr>\n<tr>\n<td>Output Shaft Diameter (in)<\/td>\n<td>1.25<\/td>\n<\/tr>\n<tr>\n<td>Output Shaft Diameter (mm)<\/td>\n<td>31.75<\/td>\n<\/tr>\n<tr>\n<td>Deal Contents<\/td>\n<td>Gear, Instruction Sheet (2), Flushing Instruction, Instruction Tag, Sealing Kit<\/td>\n<\/tr>\n<tr>\n<td>Pitman Arm Provided<\/td>\n<td>No<\/td>\n<\/tr>\n<tr>\n<td>Force Port ID Dimensions<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Pressure Port Thread Dimension<\/td>\n<td>M18 x 1.five<\/td>\n<\/tr>\n<tr>\n<td>Product Problem<\/td>\n<td>Remanufactured<\/td>\n<\/tr>\n<tr>\n<td>Solution Packing Weight<\/td>\n<td>29.ninety six lbs<\/td>\n<\/tr>\n<tr>\n<td>Pump Rotation<\/td>\n<td>Reverse<\/td>\n<\/tr>\n<tr>\n<td>Return Port ID Size<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td>Return Port Thread Dimension<\/td>\n<td>M16 x 1.five<\/td>\n<\/tr>\n<tr>\n<td>Steering Box Sort<\/td>\n<td>Electricity Steering<\/td>\n<\/tr>\n<tr>\n<td>Whole Turns Lock to Lock<\/td>\n<td>two.6 to 3.3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><p>\u00a0<\/p>\n<p>\n<p>\n<p>\u00a0<\/p>\n<p>\n<p>\n<p>\n<p>\n<p>\n<p>\n<p>automobile compatibility<\/p>\n<p>\n<table>\n<tbody>\n<tr>\n<td>2002 &#8211; 1996<\/td>\n<td>Chevrolet<\/td>\n<td>Express 2500<\/td>\n<\/tr>\n<tr>\n<td>2002 &#8211; 1996<\/td>\n<td>Chevrolet<\/td>\n<td>Categorical 3500<\/td>\n<\/tr>\n<tr>\n<td>1994<\/td>\n<td>Dodge<\/td>\n<td>B150<\/td>\n<\/tr>\n<tr>\n<td>1998 &#8211; 1995<\/td>\n<td>Dodge<\/td>\n<td>B1500<\/td>\n<\/tr>\n<tr>\n<td>1994<\/td>\n<td>Dodge<\/td>\n<td>B250<\/td>\n<\/tr>\n<tr>\n<td>1998 &#8211; 1995<\/td>\n<td>Dodge<\/td>\n<td>B2500<\/td>\n<\/tr>\n<tr>\n<td>1994<\/td>\n<td>Dodge<\/td>\n<td>B350<\/td>\n<\/tr>\n<tr>\n<td>1998 &#8211; 1995<\/td>\n<td>Dodge<\/td>\n<td>B3500<\/td>\n<\/tr>\n<tr>\n<td>1998 &#8211; 1995<\/td>\n<td>Dodge<\/td>\n<td>Ram 1500 Van<\/td>\n<\/tr>\n<tr>\n<td>1998 &#8211; 1996<\/td>\n<td>Dodge<\/td>\n<td>Ram 2500 Van<\/td>\n<\/tr>\n<tr>\n<td>1998 &#8211; 1996<\/td>\n<td>Dodge<\/td>\n<td>Ram 3500 Van<\/td>\n<\/tr>\n<tr>\n<td>2002 &#8211; 1996<\/td>\n<td>GMC<\/td>\n<td>Savana 2500<\/td>\n<\/tr>\n<tr>\n<td>2002 &#8211; 1996<\/td>\n<td>GMC<\/td>\n<td>Savana 3500<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><p>\u00a0<\/p>\n<p>\n<p>\n<p>\n<p>\n<p>\u00a0  <\/p>\n<p>\n<p>\n<p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Service apr\u00e8s-vente :<\/th>\n<td>Life Service<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Garantie:<\/th>\n<td>12 mois<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Taper:<\/th>\n<td>Bo\u00eetier de direction\/Arbre<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Mat\u00e9riel:<\/th>\n<td>Iron<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Certification :<\/th>\n<td>ISO<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Automatique:<\/th>\n<td>Automatique<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Exemples :<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 155\/Piece<\/strong><br \/>\n                                        <span title=\"1 pi\u00e8ce (commande minimale)\">1 pi\u00e8ce (commande minimale)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <a class=\"\" target=\"_blank\" href=\" \" rel=\"nofollow noopener\"><i class=\"ob-icon icon-product\"><\/i>Demande d'\u00e9chantillon<\/a>\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personnalisation\u00a0:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponible\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i>Demande personnalis\u00e9e<br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Color<\/td>\n<td style=\"text-align:center\">Black<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">E-Waste<\/td>\n<td style=\"text-align:center\">No<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Hose Port Type<\/td>\n<td style=\"text-align:center\">O-Ring<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Input Shaft Diameter (in)<\/td>\n<td style=\"text-align:center\">0.73<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Input Shaft Diameter (mm)<\/td>\n<td style=\"text-align:center\">18.42<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Input Shaft Spline Count<\/td>\n<td style=\"text-align:center\">25 + Flat &amp; Groove<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Input Shaft Type<\/td>\n<td style=\"text-align:center\">Splined, Single Flat<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Number of Mounting Holes<\/td>\n<td style=\"text-align:center\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Output Shaft Diameter (in)<\/td>\n<td style=\"text-align:center\">1.25<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Output Shaft Diameter (mm)<\/td>\n<td style=\"text-align:center\">31.75<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Package Contents<\/td>\n<td style=\"text-align:center\">Gear, Instruction Sheet (2), Flushing Instruction, Instruction Tag, Sealing Kit<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Pitman Arm Included<\/td>\n<td style=\"text-align:center\">No<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Pressure Port ID Size<\/td>\n<td style=\"text-align:center\">0<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Pressure Port Thread Size<\/td>\n<td style=\"text-align:center\">M18 x 1.5<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Product Condition<\/td>\n<td style=\"text-align:center\">Remanufactured<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Product Packing Weight<\/td>\n<td style=\"text-align:center\">29.96 lbs<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Pump Rotation<\/td>\n<td style=\"text-align:center\">Reverse<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Return Port ID Size<\/td>\n<td style=\"text-align:center\">0<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Return Port Thread Size<\/td>\n<td style=\"text-align:center\">M16 x 1.5<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Steering Box Type<\/td>\n<td style=\"text-align:center\">Power Steering<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Total Turns Lock to Lock<\/td>\n<td style=\"text-align:center\">2.6 to 3.3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td style=\"text-align:center\">2002 &#8211; 1996<\/td>\n<td style=\"text-align:center\">Chevrolet<\/td>\n<td style=\"text-align:center\">Express 2500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">2002 &#8211; 1996<\/td>\n<td style=\"text-align:center\">Chevrolet<\/td>\n<td style=\"text-align:center\">Express 3500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1994<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B150<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1995<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B1500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1994<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B250<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1995<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B2500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1994<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B350<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1995<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B3500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1995<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">Ram 1500 Van<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1996<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">Ram 2500 Van<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1996<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">Ram 3500 Van<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">2002 &#8211; 1996<\/td>\n<td style=\"text-align:center\">GMC<\/td>\n<td style=\"text-align:center\">Savana 2500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">2002 &#8211; 1996<\/td>\n<td style=\"text-align:center\">GMC<\/td>\n<td style=\"text-align:center\">Savana 3500<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Service apr\u00e8s-vente :<\/th>\n<td>Life Service<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Garantie:<\/th>\n<td>12 mois<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Taper:<\/th>\n<td>Bo\u00eetier de direction\/Arbre<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Mat\u00e9riel:<\/th>\n<td>Iron<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Certification :<\/th>\n<td>ISO<\/td>\n<\/tr>\n<tr>\n<th width=\"160\" class=\"th-label\">Automatique:<\/th>\n<td>Automatique<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Exemples :<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                        <strong class=\"red\">US$ 155\/Piece<\/strong><br \/>\n                                        <span title=\"1 pi\u00e8ce (commande minimale)\">1 pi\u00e8ce (commande minimale)<\/span>\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                                                                    <a class=\"\" target=\"_blank\" href=\" \" rel=\"nofollow noopener\"><i class=\"ob-icon icon-product\"><\/i>Demande d'\u00e9chantillon<\/a>\n                                                                            <\/div>\n<div class=\"sample-order-desc\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<th width=\"160\" class=\"th-label\">Personnalisation\u00a0:<\/th>\n<td>\n<div class=\"sample-order-info\">\n<div class=\"info-text\">\n                                            Disponible\n                                        <\/div>\n<p>                                        <span class=\"gap\">|<\/span><br \/>\n                                        <a target=\"_blank\" rel=\"nofollow noopener\" href=\" \"><br \/>\n                                        <i class=\"ob-icon icon-fill\"><\/i>Demande personnalis\u00e9e<br \/>\n                                        <\/a>\n                                    <\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Color<\/td>\n<td style=\"text-align:center\">Black<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">E-Waste<\/td>\n<td style=\"text-align:center\">No<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Hose Port Type<\/td>\n<td style=\"text-align:center\">O-Ring<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Input Shaft Diameter (in)<\/td>\n<td style=\"text-align:center\">0.73<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Input Shaft Diameter (mm)<\/td>\n<td style=\"text-align:center\">18.42<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Input Shaft Spline Count<\/td>\n<td style=\"text-align:center\">25 + Flat &amp; Groove<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Input Shaft Type<\/td>\n<td style=\"text-align:center\">Splined, Single Flat<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Number of Mounting Holes<\/td>\n<td style=\"text-align:center\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Output Shaft Diameter (in)<\/td>\n<td style=\"text-align:center\">1.25<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Output Shaft Diameter (mm)<\/td>\n<td style=\"text-align:center\">31.75<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Package Contents<\/td>\n<td style=\"text-align:center\">Gear, Instruction Sheet (2), Flushing Instruction, Instruction Tag, Sealing Kit<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Pitman Arm Included<\/td>\n<td style=\"text-align:center\">No<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Pressure Port ID Size<\/td>\n<td style=\"text-align:center\">0<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Pressure Port Thread Size<\/td>\n<td style=\"text-align:center\">M18 x 1.5<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Product Condition<\/td>\n<td style=\"text-align:center\">Remanufactured<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Product Packing Weight<\/td>\n<td style=\"text-align:center\">29.96 lbs<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Pump Rotation<\/td>\n<td style=\"text-align:center\">Reverse<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Return Port ID Size<\/td>\n<td style=\"text-align:center\">0<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Return Port Thread Size<\/td>\n<td style=\"text-align:center\">M16 x 1.5<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Steering Box Type<\/td>\n<td style=\"text-align:center\">Power Steering<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color:#e6e7e8;text-align:center\">Total Turns Lock to Lock<\/td>\n<td style=\"text-align:center\">2.6 to 3.3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>###<\/p>\n<table class=\"widefat\" id=\"add_new_publishing_attribute\">\n<tbody>\n<tr>\n<td style=\"text-align:center\">2002 &#8211; 1996<\/td>\n<td style=\"text-align:center\">Chevrolet<\/td>\n<td style=\"text-align:center\">Express 2500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">2002 &#8211; 1996<\/td>\n<td style=\"text-align:center\">Chevrolet<\/td>\n<td style=\"text-align:center\">Express 3500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1994<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B150<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1995<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B1500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1994<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B250<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1995<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B2500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1994<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B350<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1995<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">B3500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1995<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">Ram 1500 Van<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1996<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">Ram 2500 Van<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">1998 &#8211; 1996<\/td>\n<td style=\"text-align:center\">Dodge<\/td>\n<td style=\"text-align:center\">Ram 3500 Van<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">2002 &#8211; 1996<\/td>\n<td style=\"text-align:center\">GMC<\/td>\n<td style=\"text-align:center\">Savana 2500<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align:center\">2002 &#8211; 1996<\/td>\n<td style=\"text-align:center\">GMC<\/td>\n<td style=\"text-align:center\">Savana 3500<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><h2>Types d'engrenages coniques<\/h2>\n<p>Les engrenages coniques sont utilis\u00e9s dans de nombreux secteurs industriels. On les retrouve notamment dans les excavatrices sur roues, les dragues, les convoyeurs, les actionneurs de broyeurs et les transmissions ferroviaires. Leur denture conique, h\u00e9lico\u00efdale ou angulaire, les rend particuli\u00e8rement adapt\u00e9s aux espaces restreints. Ils sont \u00e9galement utilis\u00e9s en robotique et comme supports verticaux pour les laminoirs. Enfin, les engrenages coniques trouvent des applications dans l'industrie agroalimentaire. Pour en savoir plus sur les engrenages coniques, poursuivez votre lecture.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gear\/t-gear-2.webp\" alt=\"engrenage\" width=\"800\" \/><\/p>\n<h2>engrenage conique \u00e0 denture h\u00e9lico\u00efdale<\/h2>\n<p>Les engrenages coniques \u00e0 denture spirale servent \u00e0 transmettre la puissance entre deux arbres \u00e0 angle droit. Ils poss\u00e8dent des dents courbes ou obliques et peuvent \u00eatre fabriqu\u00e9s \u00e0 partir de divers m\u00e9taux. Bestagear est un fabricant sp\u00e9cialis\u00e9 dans les engrenages coniques \u00e0 denture spirale de moyenne et grande taille. Ils sont utilis\u00e9s dans les secteurs minier, m\u00e9tallurgique, maritime et p\u00e9trolier. Les engrenages coniques \u00e0 denture spirale sont g\u00e9n\u00e9ralement fabriqu\u00e9s en acier, en aluminium ou en mat\u00e9riaux ph\u00e9noliques.<br \/>Les engrenages coniques \u00e0 denture spirale pr\u00e9sentent de nombreux avantages. Leur engr\u00e8nement assure une transmission de force plus progressive. Extr\u00eamement robustes, ils sont con\u00e7us pour une longue dur\u00e9e de vie. De plus, ils sont moins chers que les autres engrenages \u00e0 angle droit. Leur fabrication par paires contribue \u00e9galement \u00e0 leur long\u00e9vit\u00e9. Enfin, les engrenages coniques \u00e0 denture spirale r\u00e9duisent le bruit et les vibrations. Par cons\u00e9quent, si vous avez besoin d'un nouveau jeu d'engrenages, les engrenages coniques \u00e0 denture spirale constituent le choix id\u00e9al.<br \/>Le contact entre les dents d'un engrenage conique \u00e0 denture spirale s'effectue \u00e0 la surface de la dent. Ce contact ob\u00e9it \u00e0 la th\u00e9orie de Hertz du contact \u00e9lastique. Ce principe est valable pour de faibles dimensions de la zone de contact et de faibles rayons de courbure relatifs des surfaces. Dans ce cas, les contraintes et le frottement sont n\u00e9gligeables. Un engrenage conique \u00e0 denture spirale est un exemple courant d'engrenage h\u00e9lico\u00efdal invers\u00e9. Ce type d'engrenage est fr\u00e9quemment utilis\u00e9 dans les \u00e9quipements miniers.<br \/>Les engrenages coniques \u00e0 denture spirale poss\u00e8dent \u00e9galement un syst\u00e8me d'absorption du jeu. Ce syst\u00e8me contribue \u00e0 maintenir l'\u00e9paisseur du film d'huile sur la surface de la dent. Les erreurs d'axe, de distance de montage et d'angle influent sur le contact des dents d'un engrenage conique \u00e0 denture spirale. Le r\u00e9glage du jeu permet de corriger ces probl\u00e8mes. Les tol\u00e9rances indiqu\u00e9es ci-dessus sont courantes pour les engrenages coniques. Dans certains cas, les fabricants apportent de l\u00e9g\u00e8res modifications de conception en fin de production, ce qui minimise les risques pour les \u00e9quipementiers.<\/p>\n<h2>engrenage conique droit<\/h2>\n<p>Les engrenages coniques droits comptent parmi les types d'engrenages les plus faciles \u00e0 fabriquer. La premi\u00e8re m\u00e9thode de fabrication consistait \u00e0 utiliser une raboteuse \u00e9quip\u00e9e d'une t\u00eate d'indexage. Cependant, des am\u00e9liorations ont \u00e9t\u00e9 apport\u00e9es aux m\u00e9thodes de fabrication suite \u00e0 l'introduction des syst\u00e8mes Revacycle et Coniflex. Les technologies les plus r\u00e9centes permettent une fabrication encore plus pr\u00e9cise. CZPT utilise ces deux m\u00e9thodes de fabrication. Voici quelques exemples de fabrication d'engrenages coniques droits.<br \/>Un engrenage conique droit est fabriqu\u00e9 selon deux m\u00e9thodes de biseautage\u00a0: la m\u00e9thode Gleason et la m\u00e9thode Klingelnberg. La m\u00e9thode Gleason est la plus courante. Contrairement \u00e0 d'autres types d'engrenages, la m\u00e9thode CZPT n'est pas une norme universelle. Le syst\u00e8me Gleason permet d'obtenir des engrenages de meilleure qualit\u00e9, car le bombage des dents est la m\u00e9thode la plus efficace pour fabriquer des engrenages tol\u00e9rant m\u00eame de petites erreurs d'assemblage. Il \u00e9limine \u00e9galement la concentration des contraintes sur les bords biseaut\u00e9s des dents.<br \/>La composition de l'engrenage d\u00e9pend de son application. Lorsque la durabilit\u00e9 est primordiale, on utilise la fonte. Le pignon est g\u00e9n\u00e9ralement trois fois plus dur que la roue, ce qui contribue \u00e0 \u00e9quilibrer l'usure. D'autres mat\u00e9riaux, comme l'acier au carbone, sont moins co\u00fbteux, mais moins r\u00e9sistants \u00e0 la corrosion. L'inertie est un autre facteur crucial, car des engrenages plus lourds sont plus difficiles \u00e0 inverser et \u00e0 arr\u00eater. Les exigences de pr\u00e9cision peuvent concerner le module et le diam\u00e8tre de l'engrenage, ainsi que l'angle de pression.<br \/>La g\u00e9om\u00e9trie en d\u00e9veloppante d'une dent conique droite est souvent calcul\u00e9e en faisant varier la normale \u00e0 la surface. Ce calcul prend en compte les coordonn\u00e9es de la surface et l'\u00e9paisseur th\u00e9orique de la dent. \u00c0 l'aide d'une machine \u00e0 mesurer tridimensionnelle (MMT), la surface sph\u00e9rique en d\u00e9veloppante permet de d\u00e9terminer les profils de contact des dents. Cette m\u00e9thode est particuli\u00e8rement utile lorsqu'un banc d'essai de roulement n'est pas disponible, car elle permet de pr\u00e9dire le profil de contact des dents.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gear\/c-gear-2.webp\" alt=\"engrenage\" width=\"800\" \/><\/p>\n<h2>engrenage conique hypo\u00efde<\/h2>\n<p>Les engrenages hypo\u00efdes coniques constituent une solution de r\u00e9duction de vitesse efficace et polyvalente. Leur compacit\u00e9, leur rendement \u00e9lev\u00e9, leur faible niveau sonore et de d\u00e9gagement de chaleur, ainsi que leur longue dur\u00e9e de vie en font un choix privil\u00e9gi\u00e9 dans les secteurs de la transmission de puissance et du contr\u00f4le de mouvement. Vous trouverez ci-dessous quelques-uns des avantages des engrenages hypo\u00efdes et les raisons de leur utilisation. Nous aborderons \u00e9galement ci-dessous les principales id\u00e9es re\u00e7ues et les fausses hypoth\u00e8ses concernant ce type d'engrenage. Ces affirmations peuvent para\u00eetre contre-intuitives au premier abord, mais elles vous aideront \u00e0 mieux comprendre son fonctionnement.<br \/>Le principe de base des engrenages hypo\u00efdes repose sur l'utilisation de deux arbres non s\u00e9cants. L'arbre de la roue dent\u00e9e la plus petite est d\u00e9cal\u00e9 par rapport \u00e0 celui de la roue dent\u00e9e la plus grande, ce qui leur permet de s'engr\u00e8ner sans interf\u00e9rence et de se soutenir mutuellement efficacement. Le transfert de couple qui en r\u00e9sulte est am\u00e9lior\u00e9 par rapport aux engrenages conventionnels. Un engrenage conique hypo\u00efde est utilis\u00e9 pour entra\u00eener l'essieu arri\u00e8re d'une automobile. Il accro\u00eet la flexibilit\u00e9 de conception des machines et permet un r\u00e9glage pr\u00e9cis des axes.<br \/>Dans le premier cas, l'engr\u00e8nement des deux corps est obtenu en ajustant la fraise hyperbolique \u00e0 la roue dent\u00e9e souhait\u00e9e. Ses propri\u00e9t\u00e9s g\u00e9om\u00e9triques, son orientation et sa position d\u00e9terminent cette roue dent\u00e9e. Cette derni\u00e8re est utilis\u00e9e si la roue dent\u00e9e souhait\u00e9e est silencieuse ou si elle doit r\u00e9duire les vibrations. Une fraise hyperbolique, quant \u00e0 elle, s'engr\u00e8ne avec deux corps dent\u00e9s. C'est l'option la plus efficace pour mod\u00e9liser les engrenages hypo\u00efdes pr\u00e9sentant des probl\u00e8mes de bruit.<br \/>La principale diff\u00e9rence entre les engrenages hypo\u00efdes et les engrenages coniques \u00e0 denture spirale r\u00e9side dans le diam\u00e8tre\u00a0: les premiers ont un diam\u00e8tre sup\u00e9rieur. On les trouve g\u00e9n\u00e9ralement dans des applications \u00e0 rapport de r\u00e9duction de 1:1 et 2:1, mais certains fabricants proposent \u00e9galement des rapports plus \u00e9lev\u00e9s. Un r\u00e9ducteur hypo\u00efde peut atteindre des vitesses de 3\u00a0000\u00a0tr\/min, ce qui en fait un choix privil\u00e9gi\u00e9 pour de nombreuses applications. Ainsi, si vous recherchez un r\u00e9ducteur \u00e0 haut rendement, c'est l'engrenage qu'il vous faut.<\/p>\n<h2>angles d'addendum et de dedendum<\/h2>\n<p>Les angles d'addendum et de dedendum d'un engrenage conique servent \u00e0 d\u00e9crire la forme et la profondeur de ses dents. Chaque dent pr\u00e9sente une surface l\u00e9g\u00e8rement conique dont la profondeur varie. Ces angles sont d\u00e9finis par leurs distances d'addendum et de dedendum. L'angle d'addendum correspond \u00e0 la distance entre la face sup\u00e9rieure et la face inf\u00e9rieure de la dent, tandis que l'angle de dedendum correspond \u00e0 la distance entre la face primitive et la face inf\u00e9rieure de la dent.<br \/>L'angle primitif est l'angle form\u00e9 par le sommet du c\u00f4ne primitif de la roue dent\u00e9e et la ligne primitive de l'arbre. L'angle de dendum, quant \u00e0 lui, correspond \u00e0 la profondeur de l'espace entre les dents sous la ligne primitive. Ces deux angles servent \u00e0 caract\u00e9riser la forme d'une roue dent\u00e9e conique. Les angles de addendum et de dendum sont essentiels pour la conception des engrenages.<br \/>Les angles de dendum et de addendum d'un engrenage conique sont d\u00e9termin\u00e9s par le rapport de contact (Mc) des deux engrenages. La d\u00e9veloppante de cercle ne doit pas d\u00e9passer le diam\u00e8tre de base de l'engrenage conique. Ce diam\u00e8tre est \u00e9galement une dimension critique pour la conception d'un engrenage. Il est possible de r\u00e9duire la d\u00e9veloppante de cercle pour qu'elle corresponde \u00e0 la d\u00e9veloppante de cercle d'origine, mais elle doit alors lui \u00eatre tangente.<br \/>L'application la plus courante des engrenages coniques est le diff\u00e9rentiel automobile. On les retrouve dans de nombreux types de v\u00e9hicules, notamment les voitures, les camions et m\u00eame les engins de chantier. Ils sont \u00e9galement utilis\u00e9s dans le secteur maritime et l'a\u00e9ronautique. Outre ces deux utilisations principales, les engrenages coniques ont de nombreuses autres applications et leur popularit\u00e9 ne cesse de cro\u00eetre. Ils constituent un \u00e9l\u00e9ment essentiel des syst\u00e8mes d'engrenages automobiles et industriels.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/gear\/b-gear-2.webp\" alt=\"engrenage\" width=\"800\" \/><\/p>\n<h2>Applications des engrenages coniques<\/h2>\n<p>Les engrenages coniques sont utilis\u00e9s dans de nombreuses applications. Ils sont fabriqu\u00e9s \u00e0 partir de divers mat\u00e9riaux en fonction de leur poids, de la charge et de leur utilisation. Pour les applications \u00e0 forte charge, on utilise des m\u00e9taux ferreux comme la fonte grise. Ces mat\u00e9riaux offrent une excellente r\u00e9sistance \u00e0 l'usure et sont peu co\u00fbteux. Pour les applications \u00e0 faible charge, on utilise l'acier ou des mat\u00e9riaux non m\u00e9talliques comme les plastiques. Certains mat\u00e9riaux pour engrenages coniques sont consid\u00e9r\u00e9s comme silencieux. Voici quelques-unes de leurs utilisations les plus courantes.<br \/>Les engrenages coniques droits sont les plus faciles \u00e0 fabriquer. La premi\u00e8re m\u00e9thode de fabrication consistait \u00e0 utiliser une raboteuse \u00e0 t\u00eate d'indexage. Les m\u00e9thodes de fabrication modernes ont introduit les syst\u00e8mes Revacycle et Coniflex. Pour la fabrication d'engrenages industriels, CZPT utilise le syst\u00e8me Revacycle. Il existe cependant de nombreux types d'engrenages coniques. Ce guide vous aidera \u00e0 choisir le mat\u00e9riau adapt\u00e9 \u00e0 votre prochain projet. Ces mat\u00e9riaux r\u00e9sistent \u00e0 des vitesses de rotation \u00e9lev\u00e9es et sont tr\u00e8s robustes.<br \/>Les engrenages coniques sont tr\u00e8s r\u00e9pandus dans l'automobile et les machines industrielles. Ils relient l'arbre de transmission aux roues. Certains pr\u00e9sentent m\u00eame un angle de 45 degr\u00e9s. Ces engrenages peuvent \u00eatre mont\u00e9s sur une surface conique afin de tester leurs performances de transmission. Ils sont \u00e9galement utilis\u00e9s dans des applications de test pour garantir une transmission de mouvement optimale. Ils permettent de r\u00e9duire la vitesse des arbres droits. Les engrenages coniques sont utilis\u00e9s dans de nombreux secteurs, du maritime \u00e0 l'a\u00e9ronautique.<br \/>Le type d'engrenage conique le plus simple est l'engrenage \u00e0 denture droite, dont le rapport est de 1:1. Il sert \u00e0 modifier l'axe de rotation. Les arbres des engrenages coniques \u00e0 denture droite peuvent se croiser selon n'importe quel angle, de 45\u00b0 \u00e0 120\u00b0. Les dents de cet engrenage peuvent \u00eatre droites, h\u00e9lico\u00efdales ou Zerol. Comme pour les syst\u00e8mes pignon-cr\u00e9maill\u00e8re, il existe diff\u00e9rents types d'engrenages coniques.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/GearRack\/GearRack-1.webp\" alt=\"China OEM 15062968 Auto Spare Parts Steering Rack for Gmc Savana 2500 3500     duty gear rack\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/GearRack\/GearRack-2.webp\" alt=\"China OEM 15062968 Auto Spare Parts Steering Rack for Gmc Savana 2500 3500     duty gear rack\"><br \/>editor by czh 2023-01-24<\/p>","protected":false},"excerpt":{"rendered":"<p>Solution Description Solution Description Colour Black E-Waste No Hose Port Variety O-Ring Input Shaft Diameter (in) .seventy three Input Shaft Diameter (mm) eighteen.42 Enter Shaft Spline Count 25 + Flat &amp; Groove Enter Shaft Kind Splined, One Flat Amount of Mounting Holes 3 Output Shaft Diameter (in) 1.25 Output Shaft Diameter (mm) 31.75 Deal Contents [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[2128,3389,484,887,1793,2474,889,2637,3395],"class_list":["post-1070","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-auto-gear","tag-auto-steering-gear","tag-gear","tag-gear-parts","tag-gear-rack","tag-oem-gear","tag-parts-gear","tag-spare-parts-gear","tag-steering-gear"],"_links":{"self":[{"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/posts\/1070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/comments?post=1070"}],"version-history":[{"count":0,"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/posts\/1070\/revisions"}],"wp:attachment":[{"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/media?parent=1070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/categories?post=1070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gearrack.top\/fr\/wp-json\/wp\/v2\/tags?post=1070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}